{"id":10698,"date":"2026-03-08T08:15:58","date_gmt":"2026-03-08T11:15:58","guid":{"rendered":"https:\/\/visit7wonders.com\/es\/?p=10698"},"modified":"2026-03-08T08:14:23","modified_gmt":"2026-03-08T11:14:23","slug":"china-the-dizzying-heights-of-the-great-wall-of-simatai-attract-tourists","status":"publish","type":"post","link":"https:\/\/visit7wonders.com\/es\/2026\/03\/08\/china-the-dizzying-heights-of-the-great-wall-of-simatai-attract-tourists\/","title":{"rendered":"China: Las vertiginosas alturas de la Gran Muralla de Simatai atraen a los turistas"},"content":{"rendered":"<p>La secci\u00f3n de Simatai de la Gran Muralla, en las afueras de Beijing, es famosa por su escarpado desnivel.<\/p>\n<p>La secci\u00f3n se construy\u00f3 originalmente durante la dinast\u00eda Qi del Norte (550-577) y se reconstruy\u00f3 durante la dinast\u00eda Ming (1368-1644).<\/p>\n<p>Esta muralla protege el acceso a Gubeikou, un importante paso estrat\u00e9gico en la ruta hacia la antigua capital.<\/p>\n<p>Por sus caracter\u00edsticas, las vertiginosas alturas de la Gran Muralla de Simatai, atraen gran cantidad de turistas durante todo el a\u00f1o.<\/p>\n<p>La Gran Muralla china es una de las Nuevas 7 Maravillas del Mundo y es sin dudas, el lugar m\u00e1s atractivo para los turistas que llegan desde todo el mundo.<\/p>\n<p>Esta muralla es una antigua forticaci\u00f3n china construida y reconstruida entre el siglo V a.C. y el siglo XVI para proteger la frontera norte del imperio chino durante las sucesivas dinast\u00edas imperiales de los ataques de los n\u00f3madas xiongnu de Mongolia y Manchuria.<\/p>\n<p>Contando sus ramificaciones y construcciones secundarias, se calcula que tiene unos 21.200 km de longitud, desde la frontera con Corea al borde del r\u00edo Yalu, hasta el desierto de Gobi. En promedio, mide unos 7 metros de alto y unos 5 metros de ancho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La secci\u00f3n de Simatai de la Gran Muralla, en las afueras de Beijing, es famosa por su escarpado desnivel. La secci\u00f3n se construy\u00f3 originalmente durante&hellip;<\/p>\n","protected":false},"author":17,"featured_media":10699,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,318,312],"tags":[],"class_list":["post-10698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-china","category-gran-muralla-china","category-new-7-wonders-of-the-world-2"],"_links":{"self":[{"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/posts\/10698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/comments?post=10698"}],"version-history":[{"count":4,"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/posts\/10698\/revisions"}],"predecessor-version":[{"id":10703,"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/posts\/10698\/revisions\/10703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/media\/10699"}],"wp:attachment":[{"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/media?parent=10698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/categories?post=10698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit7wonders.com\/es\/wp-json\/wp\/v2\/tags?post=10698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}